{"id":692,"count":1,"description":"","link":"https:\/\/westpenetone.com\/en\/applications\/thermally-stable-sulfide-scavenger\/","name":"Thermally stable sulfide scavenger","slug":"thermally-stable-sulfide-scavenger","taxonomy":"applications","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/westpenetone.com\/en\/wp-json\/wp\/v2\/applications\/692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/westpenetone.com\/en\/wp-json\/wp\/v2\/applications"}],"about":[{"href":"https:\/\/westpenetone.com\/en\/wp-json\/wp\/v2\/taxonomies\/applications"}]}}